{"id":81712,"date":"2026-03-05T22:34:08","date_gmt":"2026-03-05T20:34:08","guid":{"rendered":"https:\/\/tassosmitropoulos.com\/product\/jacket-francie\/"},"modified":"2026-03-08T12:26:02","modified_gmt":"2026-03-08T10:26:02","slug":"jacket-francie","status":"publish","type":"product","link":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/","title":{"rendered":"JACKET FRANCIE"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;]<\/p>\n<ul>\n<li>97%COT 3%EL<\/li>\n<li data-start=\"2\" data-end=\"39\">Denim jacket with a military aesthetic<\/li>\n<li data-start=\"42\" data-end=\"93\">Stand collar with zip and button closure<\/li>\n<li data-start=\"96\" data-end=\"153\">Four front cargo pockets decorated with rhinestones<\/li>\n<li data-start=\"156\" data-end=\"210\">Adjustable drawstring at the waist for a more fitted silhouette<\/li>\n<li data-start=\"213\" data-end=\"265\">Frayed finishes for a modern denim character<\/li>\n<li data-start=\"268\" data-end=\"330\">Statement back featuring the \u201cDEOS\u201d logo made of metal elements<\/li>\n<\/ul>\n<p>[\/vc_column_text][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;] 97%COT 3%EL Denim jacket with a military aesthetic Stand collar with zip and button closure Four<\/p>\n","protected":false},"featured_media":82465,"template":"","meta":[],"product_brand":[],"product_cat":[468,467,471],"product_tag":[],"class_list":{"0":"post-81712","1":"product","2":"type-product","3":"status-publish","4":"has-post-thumbnail","6":"product_cat-elevated-basics-en","7":"product_cat-new-arrivals-en","8":"product_cat-panoforia-eb-en","9":"pa_chroma-white","10":"pa_megethos-m-en","11":"pa_megethos-s-en","12":"pa_megethos-xl-en","14":"first","15":"instock","16":"product-type-variable"},"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>JACKET FRANCIE - Tassos Mitropoulos|Official Website<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"JACKET FRANCIE - Tassos Mitropoulos|Official Website\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;] 97%COT 3%EL Denim jacket with a military aesthetic Stand collar with zip and button closure Four\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/\" \/>\n<meta property=\"og:site_name\" content=\"Tassos Mitropoulos|Official Website\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tassosmitropoulosfashiondesigner\" \/>\n<meta property=\"article:modified_time\" content=\"2026-03-08T10:26:02+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2026\/03\/35710-35105-2A-scaled.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1707\" \/>\n\t<meta property=\"og:image:height\" content=\"2560\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/product\\\/jacket-francie\\\/\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/product\\\/jacket-francie\\\/\",\"name\":\"JACKET FRANCIE - Tassos Mitropoulos|Official Website\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/product\\\/jacket-francie\\\/#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/product\\\/jacket-francie\\\/#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/tassosmitropoulos.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/35710-35105-2A-scaled.jpg\",\"datePublished\":\"2026-03-05T20:34:08+00:00\",\"dateModified\":\"2026-03-08T10:26:02+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/product\\\/jacket-francie\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/product\\\/jacket-francie\\\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/product\\\/jacket-francie\\\/#primaryimage\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/35710-35105-2A-scaled.jpg\",\"contentUrl\":\"https:\\\/\\\/tassosmitropoulos.com\\\/wp-content\\\/uploads\\\/2026\\\/03\\\/35710-35105-2A-scaled.jpg\",\"width\":1707,\"height\":2560},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/product\\\/jacket-francie\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Shop\",\"item\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/shop-2\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"JACKET FRANCIE\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#website\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/\",\"name\":\"Tassos Mitropoulos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tassosmitropoulos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#organization\",\"name\":\"Tassos Mitropoulos\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-99height.png\",\"contentUrl\":\"https:\\\/\\\/tassosmitropoulos.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-99height.png\",\"width\":300,\"height\":99,\"caption\":\"Tassos Mitropoulos\"},\"image\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tassosmitropoulosfashiondesigner\",\"https:\\\/\\\/www.instagram.com\\\/tassosmitropoulosofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"JACKET FRANCIE - Tassos Mitropoulos|Official Website","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/","og_locale":"en_US","og_type":"article","og_title":"JACKET FRANCIE - Tassos Mitropoulos|Official Website","og_description":"[vc_row][vc_column][vc_column_text css=&#8221;&#8221; woodmart_inline=&#8221;no&#8221; text_larger=&#8221;no&#8221;] 97%COT 3%EL Denim jacket with a military aesthetic Stand collar with zip and button closure Four","og_url":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/","og_site_name":"Tassos Mitropoulos|Official Website","article_publisher":"https:\/\/www.facebook.com\/tassosmitropoulosfashiondesigner","article_modified_time":"2026-03-08T10:26:02+00:00","og_image":[{"width":1707,"height":2560,"url":"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2026\/03\/35710-35105-2A-scaled.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/","url":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/","name":"JACKET FRANCIE - Tassos Mitropoulos|Official Website","isPartOf":{"@id":"https:\/\/tassosmitropoulos.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/#primaryimage"},"image":{"@id":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/#primaryimage"},"thumbnailUrl":"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2026\/03\/35710-35105-2A-scaled.jpg","datePublished":"2026-03-05T20:34:08+00:00","dateModified":"2026-03-08T10:26:02+00:00","breadcrumb":{"@id":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/#primaryimage","url":"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2026\/03\/35710-35105-2A-scaled.jpg","contentUrl":"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2026\/03\/35710-35105-2A-scaled.jpg","width":1707,"height":2560},{"@type":"BreadcrumbList","@id":"https:\/\/tassosmitropoulos.com\/en\/product\/jacket-francie\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/tassosmitropoulos.com\/en\/"},{"@type":"ListItem","position":2,"name":"Shop","item":"https:\/\/tassosmitropoulos.com\/en\/shop-2\/"},{"@type":"ListItem","position":3,"name":"JACKET FRANCIE"}]},{"@type":"WebSite","@id":"https:\/\/tassosmitropoulos.com\/#website","url":"https:\/\/tassosmitropoulos.com\/","name":"Tassos Mitropoulos","description":"","publisher":{"@id":"https:\/\/tassosmitropoulos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tassosmitropoulos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tassosmitropoulos.com\/#organization","name":"Tassos Mitropoulos","url":"https:\/\/tassosmitropoulos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tassosmitropoulos.com\/#\/schema\/logo\/image\/","url":"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2022\/05\/logo-99height.png","contentUrl":"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2022\/05\/logo-99height.png","width":300,"height":99,"caption":"Tassos Mitropoulos"},"image":{"@id":"https:\/\/tassosmitropoulos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tassosmitropoulosfashiondesigner","https:\/\/www.instagram.com\/tassosmitropoulosofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/product\/81712","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/types\/product"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/media\/82465"}],"wp:attachment":[{"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/media?parent=81712"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/product_brand?post=81712"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/product_cat?post=81712"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/product_tag?post=81712"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}