{"id":69887,"date":"2025-04-29T15:43:25","date_gmt":"2025-04-29T13:43:25","guid":{"rendered":"https:\/\/tassosmitropoulos.com\/fw18-eterna\/"},"modified":"2025-04-30T10:51:55","modified_gmt":"2025-04-30T08:51:55","slug":"fw18-eterna","status":"publish","type":"page","link":"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/","title":{"rendered":"FW&#8217;18 | Eterna"},"content":{"rendered":"<div class=\"wpb-content-wrapper\"><p>[vc_row][vc_column][vc_row_inner][vc_column_inner]\t\t<div id=\"gallery_411\" class=\"wd-images-gallery wd-wpb wd-rs-6810d63e5454d photoswipe-images\" style=\"--wd-justify-content:center;--wd-align-items:center;\">\n\t\t\t\n\t\t\t<div class=\" wd-grid-f-col wd-masonry\" style=\"--wd-col-lg:3;--wd-col-md:3;--wd-col-sm:1;--wd-gap-lg:10px;\">\n\t\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"1\" data-width=\"2560\" data-height=\"1707\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-1200x800.jpg\" class=\"wd-gallery-image image-1\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-1200x800.jpg 1200w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-400x267.jpg 400w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-768x512.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-1536x1024.jpg 1536w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-2048x1365.jpg 2048w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-430x287.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-700x467.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-5-150x100.jpg 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"2\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-605x800.jpg\" class=\"wd-gallery-image image-2\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-6-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"3\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-605x800.jpg\" class=\"wd-gallery-image image-3\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-7-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"4\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-605x800.jpg\" class=\"wd-gallery-image image-4\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-8-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"5\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-605x800.jpg\" class=\"wd-gallery-image image-5\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-9-1-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"6\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-605x800.jpg\" class=\"wd-gallery-image image-6\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-10-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"7\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-605x800.jpg\" class=\"wd-gallery-image image-7\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-11-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"8\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-605x800.jpg\" class=\"wd-gallery-image image-8\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-12-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"9\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-605x800.jpg\" class=\"wd-gallery-image image-9\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-13-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"10\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-605x800.jpg\" class=\"wd-gallery-image image-10\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-14-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"11\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-605x800.jpg\" class=\"wd-gallery-image image-11\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-15-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"12\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-605x800.jpg\" class=\"wd-gallery-image image-12\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-16-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"13\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-605x800.jpg\" class=\"wd-gallery-image image-13\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-17-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"14\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-605x800.jpg\" class=\"wd-gallery-image image-14\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-18-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"15\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-605x800.jpg\" class=\"wd-gallery-image image-15\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-19-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"16\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-605x800.jpg\" class=\"wd-gallery-image image-16\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-20-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"17\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-605x800.jpg\" class=\"wd-gallery-image image-17\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-21-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"18\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-605x800.jpg\" class=\"wd-gallery-image image-18\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-22-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"19\" data-width=\"2560\" data-height=\"1707\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"1200\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-1200x800.jpg\" class=\"wd-gallery-image image-19\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-1200x800.jpg 1200w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-400x267.jpg 400w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-768x512.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-1536x1024.jpg 1536w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-2048x1365.jpg 2048w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-430x287.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-700x467.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-1-150x100.jpg 150w\" sizes=\"auto, (max-width: 1200px) 100vw, 1200px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"20\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-605x800.jpg\" class=\"wd-gallery-image image-20\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-2-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"21\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-605x800.jpg\" class=\"wd-gallery-image image-21\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-3-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t<div class=\"wd-gallery-item wd-col\">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t<a href=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-scaled.jpg\" data-elementor-open-lightbox=\"no\" data-index=\"22\" data-width=\"1935\" data-height=\"2560\" \n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t>\n\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t\t<img loading=\"lazy\" decoding=\"async\" width=\"605\" height=\"800\" src=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-605x800.jpg\" class=\"wd-gallery-image image-22\" alt=\"\" srcset=\"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-605x800.jpg 605w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-227x300.jpg 227w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-768x1016.jpg 768w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-1161x1536.jpg 1161w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-1548x2048.jpg 1548w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-430x569.jpg 430w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-700x926.jpg 700w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-150x198.jpg 150w, https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2025\/04\/eterna-4-scaled.jpg 1935w\" sizes=\"auto, (max-width: 605px) 100vw, 605px\" \/>\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<\/a>\n\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\n\t\t\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<\/div>\n\t\t[\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>[vc_row][vc_column][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]<\/p>\n","protected":false},"author":12,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-69887","page","type-page","status-publish","hentry"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.4 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>FW&#039;18 | Eterna - Tassos Mitropoulos|Official Website<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"FW&#039;18 | Eterna - Tassos Mitropoulos|Official Website\" \/>\n<meta property=\"og:description\" content=\"[vc_row][vc_column][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/\" \/>\n<meta property=\"og:site_name\" content=\"Tassos Mitropoulos|Official Website\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/tassosmitropoulosfashiondesigner\" \/>\n<meta property=\"article:modified_time\" content=\"2025-04-30T08:51:55+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/fw18-eterna\\\/\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/fw18-eterna\\\/\",\"name\":\"FW'18 | Eterna - Tassos Mitropoulos|Official Website\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#website\"},\"datePublished\":\"2025-04-29T13:43:25+00:00\",\"dateModified\":\"2025-04-30T08:51:55+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/fw18-eterna\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/fw18-eterna\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/fw18-eterna\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae\",\"item\":\"https:\\\/\\\/tassosmitropoulos.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"FW&#8217;18 | Eterna\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#website\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/\",\"name\":\"Tassos Mitropoulos\",\"description\":\"\",\"publisher\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/tassosmitropoulos.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#organization\",\"name\":\"Tassos Mitropoulos\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/tassosmitropoulos.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-99height.png\",\"contentUrl\":\"https:\\\/\\\/tassosmitropoulos.com\\\/wp-content\\\/uploads\\\/2022\\\/05\\\/logo-99height.png\",\"width\":300,\"height\":99,\"caption\":\"Tassos Mitropoulos\"},\"image\":{\"@id\":\"https:\\\/\\\/tassosmitropoulos.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"},\"sameAs\":[\"https:\\\/\\\/www.facebook.com\\\/tassosmitropoulosfashiondesigner\",\"https:\\\/\\\/www.instagram.com\\\/tassosmitropoulosofficial\\\/\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"FW'18 | Eterna - Tassos Mitropoulos|Official Website","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/","og_locale":"en_US","og_type":"article","og_title":"FW'18 | Eterna - Tassos Mitropoulos|Official Website","og_description":"[vc_row][vc_column][vc_row_inner][vc_column_inner][\/vc_column_inner][\/vc_row_inner][\/vc_column][\/vc_row]","og_url":"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/","og_site_name":"Tassos Mitropoulos|Official Website","article_publisher":"https:\/\/www.facebook.com\/tassosmitropoulosfashiondesigner","article_modified_time":"2025-04-30T08:51:55+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/","url":"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/","name":"FW'18 | Eterna - Tassos Mitropoulos|Official Website","isPartOf":{"@id":"https:\/\/tassosmitropoulos.com\/#website"},"datePublished":"2025-04-29T13:43:25+00:00","dateModified":"2025-04-30T08:51:55+00:00","breadcrumb":{"@id":"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/tassosmitropoulos.com\/en\/fw18-eterna\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"\u0391\u03c1\u03c7\u03b9\u03ba\u03ae","item":"https:\/\/tassosmitropoulos.com\/en\/"},{"@type":"ListItem","position":2,"name":"FW&#8217;18 | Eterna"}]},{"@type":"WebSite","@id":"https:\/\/tassosmitropoulos.com\/#website","url":"https:\/\/tassosmitropoulos.com\/","name":"Tassos Mitropoulos","description":"","publisher":{"@id":"https:\/\/tassosmitropoulos.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/tassosmitropoulos.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Organization","@id":"https:\/\/tassosmitropoulos.com\/#organization","name":"Tassos Mitropoulos","url":"https:\/\/tassosmitropoulos.com\/","logo":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/tassosmitropoulos.com\/#\/schema\/logo\/image\/","url":"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2022\/05\/logo-99height.png","contentUrl":"https:\/\/tassosmitropoulos.com\/wp-content\/uploads\/2022\/05\/logo-99height.png","width":300,"height":99,"caption":"Tassos Mitropoulos"},"image":{"@id":"https:\/\/tassosmitropoulos.com\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/tassosmitropoulosfashiondesigner","https:\/\/www.instagram.com\/tassosmitropoulosofficial\/"]}]}},"_links":{"self":[{"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/pages\/69887","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/users\/12"}],"replies":[{"embeddable":true,"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/comments?post=69887"}],"version-history":[{"count":1,"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/pages\/69887\/revisions"}],"predecessor-version":[{"id":69888,"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/pages\/69887\/revisions\/69888"}],"wp:attachment":[{"href":"https:\/\/tassosmitropoulos.com\/en\/wp-json\/wp\/v2\/media?parent=69887"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}